
Warning: Attempt to read property "ID" on string in /home/.sites/872/site8779710/web/wp-content/themes/dt-the7-child/functions.php on line 161

Warning: Attempt to read property "ID" on string in /home/.sites/872/site8779710/web/wp-content/themes/dt-the7-child/functions.php on line 161
{"id":4064,"date":"2025-07-14T10:51:45","date_gmt":"2025-07-14T08:51:45","guid":{"rendered":"https:\/\/www.duofalz.com\/produits\/accessoires\/support-solaire-photovoltaique\/"},"modified":"2025-07-21T08:16:41","modified_gmt":"2025-07-21T06:16:41","slug":"support-solaire-photovoltaique","status":"publish","type":"page","link":"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/","title":{"rendered":"Support solaire photovolta\u00efque"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<ul class=\"duofalz_produkte\"><li class=\"duofalz_header\"><ul><li>Dimension<\/li><li><div class=\"color_header\"><span class=\"colors testadimoro\"><\/span> testa di moro<\/div>\n\t<div class=\"color_header\"><span class=\"colors braun\"><\/span> marron<\/div>\n\t<div class=\"color_header\"><span class=\"colors anthrazit\"><\/span> anthracite<\/div>\n\t<div class=\"color_header\"><span class=\"colors hellgrau\"><\/span> gris clair<\/div><\/li><li><div class=\"color_header\"><span class=\"colors oxydrot\"><\/span> rouge oxyde<\/div>\n\t<div class=\"color_header\"><span class=\"colors moosgruen\"><\/span> vert mousse<\/div>\n\t<div class=\"color_header\"><span class=\"colors kupferbraun\"><\/span> marron cuivr\u00e9<\/div>\n\t<div class=\"color_header\"><span class=\"colors weiss\"><\/span> blanc<\/div><\/li><li><div class=\"color_header\"><span class=\"colors blank\"><\/span> aluminium naturel<\/div><\/li><li><\/li><\/ul><div style=\"clear:both\"><\/div><\/li><li class=\"duofalz_line singlerow\"><strong>ALUSTAR TX SUPPORT SOLAIRE<\/strong><ul><li class=\"dimension\"><span class=\"zusatz\"><\/span><\/li><li class=\"gruppe_1\"><img decoding=\"async\" class=\"arrow_duofalz\" src=\"https:\/\/www.duofalz.com\/wp-content\/uploads\/2020\/08\/arrow.png\"><\/li><li class=\"gruppe_2\"><img decoding=\"async\" class=\"arrow_duofalz\" src=\"https:\/\/www.duofalz.com\/wp-content\/uploads\/2020\/08\/arrow.png\"><\/li><li class=\"gruppe_3\"><img decoding=\"async\" class=\"arrow_duofalz\" src=\"https:\/\/www.duofalz.com\/wp-content\/uploads\/2020\/08\/arrow.png\"><\/li><li class=\"duofalz_image\"><a class=\"foobox\" rel=\"lightbox\" href=\"\"><\/a><\/li><\/ul><div style=\"clear:both\"><\/div><\/li><\/ul>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3973,"menu_order":135,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[146,149],"class_list":["post-4064","page","type-page","status-publish","hentry","category-duofalz-fr","category-support-solaire-photovoltaique","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DUOFALZ - Support solaire photovolta\u00efque<\/title>\n<meta name=\"description\" content=\"DUOFALZ vous propose des accessoires de la plus haute qualit\u00e9. Des arr\u00eats de neige aux supports solaires photovolta\u00efques \u2013 ici, vous trouverez tout ce dont vous avez besoin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DUOFALZ - Support solaire photovolta\u00efque\" \/>\n<meta property=\"og:description\" content=\"DUOFALZ vous propose des accessoires de la plus haute qualit\u00e9. Des arr\u00eats de neige aux supports solaires photovolta\u00efques \u2013 ici, vous trouverez tout ce dont vous avez besoin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/\" \/>\n<meta property=\"og:site_name\" content=\"DUOFALZ\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-21T06:16:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.duofalz.com\/wp-content\/uploads\/2020\/08\/faecher-footer.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/\",\"url\":\"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/\",\"name\":\"DUOFALZ - Support solaire photovolta\u00efque\",\"isPartOf\":{\"@id\":\"https:\/\/www.duofalz.com\/#website\"},\"datePublished\":\"2025-07-14T08:51:45+00:00\",\"dateModified\":\"2025-07-21T06:16:41+00:00\",\"description\":\"DUOFALZ vous propose des accessoires de la plus haute qualit\u00e9. Des arr\u00eats de neige aux supports solaires photovolta\u00efques \u2013 ici, vous trouverez tout ce dont vous avez besoin.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d'accueil\",\"item\":\"https:\/\/www.duofalz.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRODUITS\",\"item\":\"https:\/\/www.duofalz.com\/fr\/produits\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Accessoires\",\"item\":\"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Support solaire photovolta\u00efque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.duofalz.com\/#website\",\"url\":\"https:\/\/www.duofalz.com\/\",\"name\":\"DUOFALZ\",\"description\":\"DAS Aluminium Programm\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.duofalz.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DUOFALZ - Support solaire photovolta\u00efque","description":"DUOFALZ vous propose des accessoires de la plus haute qualit\u00e9. Des arr\u00eats de neige aux supports solaires photovolta\u00efques \u2013 ici, vous trouverez tout ce dont vous avez besoin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/","og_locale":"fr_FR","og_type":"article","og_title":"DUOFALZ - Support solaire photovolta\u00efque","og_description":"DUOFALZ vous propose des accessoires de la plus haute qualit\u00e9. Des arr\u00eats de neige aux supports solaires photovolta\u00efques \u2013 ici, vous trouverez tout ce dont vous avez besoin.","og_url":"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/","og_site_name":"DUOFALZ","article_modified_time":"2025-07-21T06:16:41+00:00","og_image":[{"width":600,"height":315,"url":"https:\/\/www.duofalz.com\/wp-content\/uploads\/2020\/08\/faecher-footer.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/","url":"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/","name":"DUOFALZ - Support solaire photovolta\u00efque","isPartOf":{"@id":"https:\/\/www.duofalz.com\/#website"},"datePublished":"2025-07-14T08:51:45+00:00","dateModified":"2025-07-21T06:16:41+00:00","description":"DUOFALZ vous propose des accessoires de la plus haute qualit\u00e9. Des arr\u00eats de neige aux supports solaires photovolta\u00efques \u2013 ici, vous trouverez tout ce dont vous avez besoin.","breadcrumb":{"@id":"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/support-solaire-photovoltaique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d'accueil","item":"https:\/\/www.duofalz.com\/fr\/"},{"@type":"ListItem","position":2,"name":"PRODUITS","item":"https:\/\/www.duofalz.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Accessoires","item":"https:\/\/www.duofalz.com\/fr\/produits\/accessoires\/"},{"@type":"ListItem","position":4,"name":"Support solaire photovolta\u00efque"}]},{"@type":"WebSite","@id":"https:\/\/www.duofalz.com\/#website","url":"https:\/\/www.duofalz.com\/","name":"DUOFALZ","description":"DAS Aluminium Programm","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.duofalz.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/pages\/4064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/comments?post=4064"}],"version-history":[{"count":2,"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/pages\/4064\/revisions"}],"predecessor-version":[{"id":4548,"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/pages\/4064\/revisions\/4548"}],"up":[{"embeddable":true,"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/pages\/3973"}],"wp:attachment":[{"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/media?parent=4064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.duofalz.com\/fr\/wp-json\/wp\/v2\/categories?post=4064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}